{"id":34825,"date":"2024-09-20T09:59:55","date_gmt":"2024-09-20T01:59:55","guid":{"rendered":"https:\/\/www.deepin.org\/?p=34825"},"modified":"2024-10-21T10:20:54","modified_gmt":"2024-10-21T02:20:54","slug":"deepin-23-receives-global-user-support","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/zh\/deepin-23-receives-global-user-support\/","title":{"rendered":"\u70ed\u7231\u65e0\u56fd\u754c\uff1adeepin 23\u83b7\u5f97\u5168\u7403\u7528\u6237\u7684\u4fe1\u4efb\u4e0e\u652f\u6301"},"content":{"rendered":"<img loading=\"lazy\" class=\"alignnone size-full wp-image-34826\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762.png\" alt=\"\" width=\"900\" height=\"383\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762.png 900w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-300x128.png 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-150x64.png 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-768x327.png 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-24x10.png 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-36x15.png 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u84dd\u8272\u79d1\u62803D\u98ce\u521b\u65b0\u79d1\u6280\u4ea7\u54c1\u8fd0\u8425\u6c99\u9f99\u6d3b\u52a8\u5ba3\u4f20\u5fae\u4fe1\u516c\u4f17\u53f7\u5c01\u9762-48x20.png 48w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>\u968f\u7740 deepin \u64cd\u4f5c\u7cfb\u7edf\u5728\u5168\u7403\u8303\u56f4\u5185\u77e5\u540d\u5ea6\u548c\u5f71\u54cd\u529b\u7684\u65e5\u76ca\u6500\u5347\uff0c\u5176\u72ec\u7279\u7684\u9b45\u529b\u548c\u5353\u8d8a\u7684\u4f7f\u7528\u4f53\u9a8c\u8d62\u5f97\u4e86\u4e16\u754c\u5404\u5730\u7684\u4f17\u591a\u5f00\u6e90\u7231\u597d\u8005\u4e0e\u5168\u7403\u5a92\u4f53\u7684\u9ad8\u5ea6\u5173\u6ce8\u4e0e\u652f\u6301\u3002<\/p>\n<p>&nbsp;<\/p>\n<section>\n<h1 style=\"text-align: center;\"><strong>\u6d77\u5916\u5206\u652f\u793e\u533a\u7684\u84ec\u52c3\u53d1\u5c55<\/strong><strong>\u00a0<\/strong><\/h1>\n<\/section>\n<section>\u6700\u8fd1\uff0cdeepin \u5728\u56fd\u9645\u5316\u8fdb\u7a0b\u4e2d\u53c8\u8fc8\u51fa\u4e86\u575a\u5b9e\u7684\u4e00\u6b65\u2014\u2014<a href=\"https:\/\/deepin.lat\/\"><strong>deepin \u5384\u74dc\u591a\u5c14\u6d77\u5916\u5206\u652f\u793e\u533a\u6b63\u5f0f\u6210\u7acb<\/strong>\uff01<\/a>\u793e\u533a\u7531\u5384\u74dc\u591a\u5c14\u96c5\u624d\u7406\u5de5\u5927\u5b66\uff08Yachay Tech University\uff09\u81ea\u53d1\u5efa\u7acb\uff0c\u8fd9\u4e00\u6210\u679c\uff0c\u4e0d\u4ec5\u6807\u5fd7\u7740 deepin \u5728\u5168\u7403\u5316\u9053\u8def\u4e0a\u7684\u53c8\u4e00\u91cd\u8981\u7a81\u7834\uff0c\u66f4\u662f deepin \u5728\u5168\u7403\u7528\u6237\u5fc3\u4e2d\u5730\u4f4d\u548c\u56fd\u9645\u5f71\u54cd\u529b\u63d0\u5347\u7684\u6709\u529b\u8bc1\u660e\u3002<\/section>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34827 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058.jpg\" alt=\"\" width=\"968\" height=\"518\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058.jpg 968w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-300x161.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-150x80.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-768x411.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-24x13.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-36x19.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094058-48x26.jpg 48w\" sizes=\"(max-width: 968px) 100vw, 968px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>deepin \u5384\u74dc\u591a\u5c14\u6d77\u5916\u5206\u652f\u793e\u533a\u7684\u5efa\u7acb\uff0c\u5fc5\u5c06\u5bf9\u8be5\u56fd\u7684\u5f00\u6e90\u793e\u533a\u53d1\u5c55\u6ce8\u5165\u4e00\u80a1\u65b0\u7684\u6d3b\u529b\u3002\u5b83\u4e0d\u4ec5\u4e3a\u5f53\u5730 deepin \u7231\u597d\u8005\u4eec\u63d0\u4f9b\u4e86\u4e00\u4e2a\u66f4\u52a0\u4fbf\u6377\u7684\u83b7\u53d6 deepin \u6700\u65b0\u8d44\u8baf\u3001\u8f6f\u4ef6\u5305\u3001\u53c2\u4e0e\u793e\u533a\u8ba8\u8bba\u7684\u5e73\u53f0\uff0c\u66f4\u4e3a\u5f53\u5730\u5176\u4ed6\u5f00\u6e90\u7231\u597d\u8005\u4eec\u4f53\u9a8c Linux \u793e\u533a\u53d1\u884c\u7248\u63d0\u4f9b\u4e86\u53c8\u4e00\u4e2a\u9009\u62e9\u3002<\/section>\n<p>&nbsp;<\/p>\n<section>\u76ee\u524d\uff0cdeepin \u5df2\u62e5\u6709\u516d\u4e2a\u5b8c\u5584\u7684\u6d77\u5916\u5206\u652f\u793e\u533a\uff0c\u5206\u522b\u4f4d\u4e8e<strong>\u897f\u73ed\u7259\u8bed\u5730\u533a\u3001\u5df4\u897f\u3001\u4fc4\u7f57\u65af\u3001\u65af\u6d1b\u4f10\u514b\u3001\u571f\u8033\u5176\u53ca\u5384\u74dc\u591a\u5c14<\/strong>\u3002\u8fd9\u4e9b\u5206\u652f\u793e\u533a\u901a\u8fc7\u8d4b\u80fd\u672c\u5730\u5316\u7684\u5185\u5bb9\u4e0e\u670d\u52a1\uff0c\u589e\u5f3a\u4e86 deepin \u5728\u8be5\u533a\u7684\u5f71\u54cd\u529b\u3002\u9664\u4e86\u4e0a\u8ff0\u516d\u5927\u5df2\u5efa\u6210\u7684\u6d77\u5916\u5206\u652f\u793e\u533a\u4e4b\u5916\uff0c<strong>\u73bb\u5229\u7ef4\u4e9a\u3001\u4e2d\u4e1c\u548c\u6cd5\u56fd<\/strong>\u7684\u5206\u652f\u793e\u533a\u4e5f\u5728\u7d27\u9523\u5bc6\u9f13\u5730\u5efa\u8bbe\u4e2d\uff0c\u6d77\u5916\u5206\u652f\u793e\u533a\u7684\u6269\u589e\u5145\u5206\u5f70\u663e\u4e86 deepin \u5728\u56fd\u9645\u5e02\u573a\u4e0a\u7684\u5f71\u54cd\u529b\uff0c\u6bcf\u4e2a\u6d77\u5916\u5206\u652f\u793e\u533a\u90fd\u662f deepin \u56fd\u9645\u5316\u6218\u7565\u7684\u91cd\u8981\u7ec4\u6210\u90e8\u5206\uff0c\u5171\u540c\u63a8\u8fdb deepin \u7684\u5168\u7403\u5316\u5efa\u8bbe\u3002<\/section>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34828 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102.jpg\" alt=\"\" width=\"992\" height=\"529\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102.jpg 992w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-300x160.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-150x80.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-768x410.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-24x13.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-36x19.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094102-48x26.jpg 48w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34829 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112.jpg\" alt=\"\" width=\"992\" height=\"529\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112.jpg 992w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-300x160.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-150x80.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-768x410.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-24x13.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-36x19.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094112-48x26.jpg 48w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<h1 style=\"text-align: center;\"><strong>\u591a\u8bed\u79cd\u56fd\u9645\u5316\u670d\u52a1\u7684\u652f\u6301<\/strong><\/h1>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<p>deepin\uff08\u6df1\u5ea6\uff09\u793e\u533a\u6b63\u79ef\u6781\u63a8\u5e7f\u5176\u56fd\u9645\u5316\u7ffb\u8bd1\u8ba1\u5212\uff0c\u6765\u81ea\u4e16\u754c\u5404\u5730\u7684\u5f00\u6e90\u7231\u597d\u8005\u4eec\u7eb7\u7eb7\u8d21\u732e\u81ea\u5df1\u7684\u529b\u91cf\uff0c\u53c2\u4e0e\u5230\u4e86 deepin \u7cfb\u7edf\u672c\u5730\u5316\u7ffb\u8bd1\u548c\u6587\u6863\u7ffb\u8bd1\u7684\u5de5\u4f5c\u4e2d\u3002deepin \u793e\u533a\u5f00\u6e90\u7231\u597d\u8005\u4eec\u81ea\u53d1\u7ec4\u5efa\u4e86\u4e94\u4e2a\u7ffb\u8bd1\u9879\u76ee\u56e2\u961f\uff0c\u6c47\u805a\u4e86\u8d85\u8fc7 1072 \u540d\u4e13\u4e1a\u7ffb\u8bd1\u5458\uff0c\u4ed6\u4eec\u643a\u624b\u5e76\u8fdb\uff0c\u5171\u540c\u4e3a deepin \u7684\u56fd\u9645\u5316\u8fdb\u7a0b\u6ce8\u5165\u4e0d\u7aed\u52a8\u529b\u3002<\/p>\n<p>\u622a\u81f3\u76ee\u524d\uff0c<strong>deepin \u64cd\u4f5c\u7cfb\u7edf\u5df2\u6210\u529f\u652f\u6301\u5305\u62ec\u7b80\u4f53\u4e2d\u6587\u3001\u82f1\u8bed\u3001\u897f\u73ed\u7259\u8bed\u3001\u4fc4\u8bed\u3001\u8461\u8404\u7259\u8bed\u3001\u6cd5\u8bed\u7b49\u5728\u5185\u7684 34 \u79cd\u8bed\u8a00<\/strong>\u3002deepin \u793e\u533a\u7279\u522b\u8bbe\u7acb\u4e86\u7ffb\u8bd1\u7fa4\u7ec4\uff0c\u4e3a\u7ffb\u8bd1\u5458\u4eec\u642d\u5efa\u4e86\u4e00\u4e2a\u9ad8\u6548\u4fbf\u6377\u7684\u4ea4\u6d41\u5e73\u53f0\uff0c\u65e8\u5728\u5171\u540c\u89e3\u51b3\u7ffb\u8bd1\u96be\u9898\uff0c\u6301\u7eed\u63d0\u5347\u7ffb\u8bd1\u8d28\u91cf\u3002<\/p>\n<p><img loading=\"lazy\" class=\"size-full wp-image-34830 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116.jpg\" alt=\"\" width=\"541\" height=\"287\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116.jpg 541w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116-300x159.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116-150x80.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116-24x13.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116-36x19.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094116-48x25.jpg 48w\" sizes=\"(max-width: 541px) 100vw, 541px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<h1 style=\"text-align: center;\"><strong>\u5168\u7403\u5a92\u4f53\u7684\u9ad8\u5ea6\u5173\u6ce8\u53ca\u62a5\u9053<\/strong><\/h1>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<p>\u968f\u7740 deepin 23 \u7684\u6b63\u5f0f\u53d1\u5e03\uff0cdeepin \u64cd\u4f5c\u7cfb\u7edf\u4f5c\u4e3a\u4e2d\u56fd Linux \u53d1\u884c\u7248\u9886\u57df\u7684\u4f7c\u4f7c\u8005\uff0c\u518d\u6b21\u5728\u56fd\u9645\u821e\u53f0\u4e0a\u8d62\u5f97\u4e86\u5168\u7403\u8303\u56f4\u5185\u5f00\u6e90\u7231\u597d\u8005\u4eec\u7684\u5e7f\u6cdb\u5173\u6ce8\u3002\u6b64\u6b21 deepin 23 \u7684\u53d1\u5e03\u4e0d\u4ec5\u5f70\u663e\u4e86 deepin \u5728\u6280\u672f\u521b\u65b0\u4e0e\u7528\u6237\u4f53\u9a8c\u65b9\u9762\u7684\u5353\u8d8a\u5b9e\u529b\uff0c\u4e5f\u8fdb\u4e00\u6b65\u5de9\u56fa\u5e76\u63d0\u5347\u4e86\u5176\u5728\u56fd\u5185\u4e43\u81f3\u5168\u7403 Linux \u684c\u9762\u53d1\u884c\u7248\u751f\u6001\u4e2d\u7684\u91cd\u8981\u5730\u4f4d\uff0c<strong>\u5728\u53d1\u5e03\u5f53\u5468\uff0c<a href=\"https:\/\/distrowatch.com\/table.php?distribution=deepin\">deepin 23 \u518d\u6b21\u8fdb\u5165 DistroWatch \u5168\u7403Linux\u53d1\u884c\u7248\u524d10\u540d<\/a><\/strong>\u3002<strong>\u8d85\u8fc76<\/strong><strong>0\u5bb6\u6765\u81ea\u5168\u7403\u82f1\u8bed\u3001\u8461\u8404\u7259\u8bed\u3001\u897f\u73ed\u7259\u8bed\u7b49\u8bed\u8a00\u5730\u533a\u7684\u5a92\u4f53<\/strong>\u5bf9 deepin 23 \u7684\u53d1\u5e03\u8fdb\u884c\u4e86\u62a5\u9053\u3002\u8fd9\u4e9b\u62a5\u9053\u4e0d\u4ec5\u6765\u81ea\u5934\u90e8\u7684\u79d1\u6280\u5a92\u4f53\uff0c\u8fd8\u6709\u7efc\u5408\u8d44\u8baf\u7c7b\u5e73\u53f0\u3002\u5404\u5bb6\u5a92\u4f53\u5728\u62a5\u9053\u4e2d\u9ad8\u5ea6\u8bc4\u4ef7\u4e86 deepin 23 \u5728\u6280\u672f\u521b\u65b0\u548c\u7528\u6237\u4f53\u9a8c\u65b9\u9762\u7684\u663e\u8457\u8fdb\u6b65\uff0c\u5c55\u73b0\u4e86 deepin 23 \u5728\u5168\u7403\u8303\u56f4\u5185\u7684\u5f71\u54cd\u529b\u3002<\/p>\n<p><strong>Linux Magazine\u3001MeuLinux\u3001Muylinux \u7b49\u56fd\u9645\u79d1\u6280\u5a92\u4f53<\/strong>\u5bf9 deepin 23 \u7684\u53d1\u5e03\u7ed9\u4e88\u4e86\u9ad8\u5ea6\u8bc4\u4ef7\u3002\u5b83\u4eec\u8ba4\u4e3a deepin 23 \u5728\u89c6\u89c9\u8bbe\u8ba1\u4e0a\u4fdd\u6301\u4e86\u7cbe\u7f8e\u98ce\u683c\uff0cdeepin\u00a0\u4f5c\u4e3a\u7b2c\u4e00\u4e2a\u96c6\u6210AI\u7684 Linux \u7cfb\u7edf\uff0cdeepin 23 \u5728\u539f\u5148\u7684\u57fa\u7840\u4e0a\u4f18\u5316\u4e86 AI \u529f\u80fd\uff0c\u4e30\u5bcc\u4e86\u7528\u6237\u4f7f\u7528\u573a\u666f\uff0c\u63d0\u5347\u4e86\u7528\u6237\u4f7f\u7528\u4f53\u9a8c\uff0c\u6210\u4e3a\u684c\u9762\u7cfb\u7edf\u9886\u57df\u7684\u521b\u65b0\u5178\u8303\u3002\u62a5\u9053\u5f3a\u8c03\u4e86 deepin 23 \u4e0d\u4ec5\u5728\u5916\u89c2\u4e0a\u8fdb\u884c\u4e86\u8c03\u6574\uff0c\u8fd8\u901a\u8fc7\u5b9e\u8d28\u6027\u7684\u529f\u80fd\u521b\u65b0\uff0c\u5982\u5168\u65b0\u7684\u539f\u5b50\u66f4\u65b0\u673a\u5236\uff0c\u4e3a\u7528\u6237\u63d0\u4f9b\u4e86\u4e0e\u5546\u4e1a\u64cd\u4f5c\u7cfb\u7edf\u76f8\u5ab2\u7f8e\u7684\u4f53\u9a8c\u3002\u6b64\u5916\uff0c\u5317\u7f8e\u7684\u591a\u5bb6\u5a92\u4f53\u4e5f\u5bf9 deepin 23 \u8868\u73b0\u51fa\u4e86\u6d53\u539a\u7684\u5174\u8da3\uff0c\u8ba4\u4e3a\u5176\u5177\u6709\u98a0\u8986\u6027\u6280\u672f\u521b\u65b0\u3002<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-34831 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120.jpg\" alt=\"\" width=\"886\" height=\"556\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120.jpg 628w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120-300x188.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120-150x94.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120-24x15.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120-36x23.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094120-48x30.jpg 48w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-34834 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136.jpg\" alt=\"\" width=\"818\" height=\"578\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136.jpg 463w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136-300x212.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136-150x106.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136-24x17.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136-36x25.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094136-48x34.jpg 48w\" sizes=\"(max-width: 818px) 100vw, 818px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<h1 style=\"text-align: center;\"><strong>\u8fd1800\u4e07\u5168\u7403\u7528\u6237\u7684\u9752\u7750<\/strong><\/h1>\n<\/section>\n<section><\/section>\n<\/section>\n<\/section>\n<\/section>\n<section><\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<p>\u5728\u5168\u7403\u8303\u56f4\u5185\uff0cdeepin \u64cd\u4f5c\u7cfb\u7edf\u5df2\u7ecf\u8d62\u5f97\u4e86\u6570\u767e\u4e07\u7528\u6237\u7684\u9752\u7750\uff0c\u4ed6\u4eec\u5f53\u4e2d\u6709\u79d1\u6280\u4e13\u5bb6\u3001\u8f6f\u4ef6\u5f00\u53d1\u8005\u3001\u6559\u80b2\u5de5\u4f5c\u8005\u548c\u666e\u901a\u7528\u6237\u3002\u4ed6\u4eec\u5bf9 deepin \u7684\u4f7f\u7528\u4fbf\u6377\u6027\u3001\u5728\u5f00\u6e90\u7406\u5ff5\u4e0a\u7684\u575a\u6301\u4ee5\u53ca\u5728\u7279\u5b9a\u573a\u666f\u4e0b\u7684\u5353\u8d8a\u6027\u80fd\u8868\u793a\u8d5e\u8d4f\u3002\u5728 YouTube \u5e73\u53f0\u4e0a\uff0c18\u4f4d\u79d1\u6280\u5a92\u4f53\u535a\u4e3b\u53d1\u5e03\u4e86 deepin 23 \u7248\u672c\u7684\u6d4b\u8bc4\u89c6\u9891\uff0c\u5206\u4eab\u4e86\u4ed6\u4eec\u7684\u5b89\u88c5\u4f53\u9a8c\u548c\u5bf9\u65b0\u529f\u80fd\u7684\u8bc4\u4ef7\u3002\u89c6\u9891\u4e2d\u5305\u542b\u4e86\u591a\u79cd\u8bed\u8a00\u548c\u5730\u533a\u7684\u8ba8\u8bba\u3002\u4e00\u4f4d\u897f\u73ed\u7259\u8bed\u535a\u4e3b\u79f0\u8d5e deepin 23 \u5728\u89c6\u89c9\u548c\u529f\u80fd\u4e0a\u7684\u8fdb\u6b65\uff0c\u79f0\u5176\u201c\u8fc5\u731b\u4e14\u521b\u65b0\u201d\u3002\u53e6\u4e00\u4f4d\u535a\u4e3b\u5219\u8be6\u7ec6\u4ecb\u7ecd\u4e86 deepin 23 \u7684\u5b89\u88c5\u6d41\u7a0b\uff0c\u5e76\u6df1\u5165\u4f53\u9a8c\u4e86 deepin 23 \u7684AI\u529f\u80fd\u548c\u5168\u65b0\u7684 DDE \u684c\u9762\u73af\u5883\u7b49\u65b0\u7279\u6027\u548c\u529f\u80fd\u3002<\/p>\n<section><img loading=\"lazy\" class=\"alignnone wp-image-34836 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152.jpg\" alt=\"\" width=\"1139\" height=\"857\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152.jpg 476w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152-300x226.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152-150x113.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094152-48x36.jpg 48w\" sizes=\"(max-width: 1139px) 100vw, 1139px\" \/><\/section>\n<section><\/section>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-34837 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156.jpg\" alt=\"\" width=\"934\" height=\"697\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156.jpg 433w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156-300x224.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156-150x112.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094156-48x36.jpg 48w\" sizes=\"(max-width: 934px) 100vw, 934px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>\u5728\u5176\u4ed6\u793e\u4ea4\u5a92\u4f53\u4e0a\uff0cdeepin 23 \u4e5f\u83b7\u5f97\u4e86\u7528\u6237\u7684\u9ad8\u5ea6\u8bc4\u4ef7\u3002\u4ed6\u4eec\u5728 Facebook\u3001X\uff08\u539fTwitter\uff09\u7b49\u5e73\u53f0\u4e0a\u5206\u4eab\u4e86 deepin 23 \u4f7f\u7528\u4f53\u9a8c\uff0c\u5e76\u5bf9 deepin 23 \u7684\u754c\u9762\u8bbe\u8ba1\u548c\u529f\u80fd\u7684\u8fdb\u6b65\u8868\u793a\u8ba4\u53ef\u3002\u7528\u6237\u4e4b\u95f4\u7684\u4e92\u5e2e\u4e92\u52a9\u6c1b\u56f4\u4fc3\u8fdb\u4e86 deepin 23 \u7684\u6210\u529f\u5b89\u88c5\u548c\u666e\u53ca\u3002\u8fd8\u6709\u4eba\u5c06 deepin 23 \u4e0e\u5176\u4ed6\u53d1\u884c\u7248\u4f5c\u6bd4\u8f83\uff0c\u8ba4\u4e3a\u5176\u5728\u89c6\u89c9\u8bbe\u8ba1\u4e0a\u8d85\u8d8a\u4e86KDE\u3001GNOME\u3001Xfce\u7b49\uff0c\u5e76\u7279\u522b\u63d0\u5230\u4e86 deepin 23 \u7684\u526a\u8d34\u677f\u3001\u622a\u56fe\u5de5\u5177\u548c\u5b89\u88c5\u9636\u6bb5\u7684\u5907\u4efd\u4e0e\u52a0\u5bc6\u529f\u80fd\u3002<\/section>\n<p>\u66f4\u6709\u7528\u6237\u6fc0\u52a8\u5730\u8868\u793a\uff0cdeepin 23 \u7684\u53d1\u5e03\u8ba9\u4ed6\u4e0b\u5b9a\u51b3\u5fc3\u5f7b\u5e95\u653e\u5f03 Windows \u7cfb\u7edf\uff0cdeepin 23 \u7684\u53d1\u5e03\u662f\u4ed6\u4eec\u7b49\u5f85\u5df2\u4e45\u7684\u91cd\u8981\u65f6\u523b\uff0c\u4ed6\u4eec\u5bf9 deepin \u7684\u7f8e\u89c2\u754c\u9762\u548c\u6613\u7528\u6027\u8868\u793a\u7531\u8877\u7684\u8d5e\u8d4f\u3002\u8fd9\u4e9b\u53cd\u9988\u5f70\u663e\u4e86 deepin 23 \u5728\u754c\u9762\u8bbe\u8ba1\u548c\u529f\u80fd\u5b9e\u7528\u6027\u4e0a\u7684\u6210\u529f\uff01<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-34838 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211.jpg\" alt=\"\" width=\"1006\" height=\"831\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211.jpg 443w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211-300x248.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211-150x124.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211-24x20.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211-36x30.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094211-48x40.jpg 48w\" sizes=\"(max-width: 1006px) 100vw, 1006px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-34839 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215.jpg\" alt=\"\" width=\"922\" height=\"765\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215.jpg 375w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215-300x249.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215-150x124.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215-24x20.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215-36x30.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/09\/\u5fae\u4fe1\u56fe\u7247_20240920094215-48x40.jpg 48w\" sizes=\"(max-width: 922px) 100vw, 922px\" \/><\/p>\n<p>&nbsp;<\/p>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<section>\n<h1 style=\"text-align: center;\"><strong>\u56fd\u9645\u63a8\u5e7f\u4e2d\u7684KOC\u529b\u91cf<\/strong><\/h1>\n<\/section>\n<section><\/section>\n<\/section>\n<\/section>\n<\/section>\n<section><\/section>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n<p>\u5728 deepin \u5168\u7403\u5316\u53d1\u5c55\u7684\u8fdb\u7a0b\u4e2d\uff0c\u4e00\u6279\u6838\u5fc3\u610f\u89c1\u7528\u6237\uff08KOC\uff09\u7684\u6301\u7eed\u8d21\u732e\u548c\u79ef\u6781\u63a8\u52a8\u8d77\u5230\u4e86\u81f3\u5173\u91cd\u8981\u7684\u4f5c\u7528\u3002\u4ed6\u4eec\u957f\u671f\u81f4\u529b\u4e8e\u9886\u5bfc\u56e2\u961f\u8fd0\u8425\u6d77\u5916\u5206\u652f\u793e\u533a\u4e0e\u793e\u7fa4\uff0c\u4e3a deepin \u5728\u5f53\u5730\u7684\u54c1\u724c\u5ba3\u4f20\u4e0e\u7528\u6237\u670d\u52a1\u505a\u51fa\u4e86\u663e\u8457\u8d21\u732e\u3002<\/p>\n<p>\u8fd8\u6709\u8bb8\u591a\u5fe0\u5b9e\u7528\u6237\u901a\u8fc7 Facebook \u7b49\u793e\u4ea4\u5e73\u53f0\u5206\u4eab\u4e2a\u4eba\u4f7f\u7528\u5fc3\u5f97\uff0c\u89e3\u7b54\u7528\u6237\u7591\u95ee\uff0c\u8fd9\u79cd\u79ef\u6781\u8ba8\u8bba\u548c\u53c2\u4e0edeepin\u793e\u533a\u5efa\u8bbe\u7684\u6c1b\u56f4\uff0c\u5438\u5f15\u4e86\u66f4\u591a\u5c0f\u4f19\u4f34\u7684\u52a0\u5165\u3002\u5176\u6b21\u5728 deepin \u82f1\u6587\u8bba\u575b\u4e0a\uff0c\u4f17\u591a\u56fd\u9645\u7248\u4e3b\u6df1\u5165\u53c2\u4e0e\u8bba\u575b\u8ba8\u8bba\uff0c\u79ef\u6781\u4e3a\u7528\u6237\u63d0\u4f9b\u6280\u672f\u5e2e\u52a9\u548c\u7591\u96be\u89e3\u7b54\uff0c\u8df5\u884c\u5f00\u6e90\u5f00\u653e\u5171\u5efa\u7684\u5f00\u6e90\u7cbe\u795e\u3002<\/p>\n<p>\u8fd9\u4e9b KOC \u7684\u65e0\u79c1\u5949\u732e\u4e0e\u9ad8\u5ea6\u53c2\u4e0e\uff0c\u5171\u540c\u6784\u5efa\u4e86\u4e00\u4e2a\u904d\u5e03\u5168\u7403\u7684\u6d3b\u8dc3 deepin \u7528\u6237\u793e\u533a\uff0c\u6709\u529b\u63a8\u52a8\u4e86 deepin \u7684\u56fd\u9645\u5316\u8fdb\u7a0b\u3002<\/p>\n<p>\u5c55\u671b\u672a\u6765\uff0cdeepin\uff08\u6df1\u5ea6\uff09\u793e\u533a\u5c06\u7ee7\u7eed\u8054\u52a8\u5168\u7403\u793e\u533a\u6210\u5458\uff0c\u5171\u540c\u5efa\u8bbe\u56fd\u9645\u77e5\u540d\u3001\u4e16\u754c\u9886\u5148\u7684\u5f00\u6e90\u793e\u533a\uff0c\u6253\u9020\u9762\u5411\u5168\u7403\u7684\u5f00\u6e90\u684c\u9762\u64cd\u4f5c\u7cfb\u7edf\u793e\u533a\u4ea7\u54c1\uff0c\u7acb\u8db3\u5f00\u6e90\uff0c\u9a71\u52a8\u521b\u65b0\uff0c\u4e0e\u672a\u6765\u540c\u884c\uff01<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1><strong>\u76f8\u5173\u9605\u8bfb\uff1a<\/strong><\/h1>\n<p>\uff081\uff09<a href=\"https:\/\/distrowatch.com\/index.php?distribution=deepin\">deepin \u5168\u7248\u672c\u955c\u50cf\u4e0b\u8f7d\uff08\u542b deepin V15\uff09<\/a><\/p>\n<p>\uff082\uff09<a href=\"https:\/\/www.deepin.org\/zh\/deepin-technical-bi-weekly-issue-1\/\">deepin \u6280\u672f\u53cc\u5468\u62a5\uff0c\u6700\u65b0\u8fdb\u5c55\u548c\u672a\u6765\u53cc\u5468\u8ba1\u5212<\/a><\/p>\n<p>\uff083\uff09<a href=\"https:\/\/www.deepin.org\/zh\/developer-community\/planning\/\">deepin 25 \u7248\u672c\u89c4\u5212<\/a><\/p>\n<p>&nbsp;<\/p>\n<article id=\"post-34816\" class=\"post-34816 post type-post status-publish format-standard hentry category-community-activities\">\n<div class=\"entry-content\">\n<p style=\"text-align: right;\">\u5185\u5bb9\u6765\u6e90\uff1adeepin\uff08\u6df1\u5ea6\uff09\u64cd\u4f5c\u7cfb\u7edf<\/p>\n<p style=\"text-align: right;\">\u8f6c\u8f7d\u8bf7\u6ce8\u660e\u51fa\u5904<\/p>\n<\/div>\n<\/article>\n<div id=\"comments\" class=\"comments-area\"><\/div>\n<p>&nbsp;","protected":false},"excerpt":{"rendered":"<p>\u968f\u7740 deepin \u64cd\u4f5c\u7cfb\u7edf\u5728\u5168\u7403\u8303\u56f4\u5185\u77e5\u540d\u5ea6\u548c\u5f71\u54cd\u529b\u7684\u65e5\u76ca\u6500\u5347\uff0c\u5176\u72ec\u7279\u7684\u9b45\u529b\u548c\u5353\u8d8a\u7684\u4f7f\u7528\u4f53\u9a8c\u8d62\u5f97\u4e86\u4e16\u754c\u5404\u5730\u7684\u4f17\u591a\u5f00\u6e90\u7231\u597d\u8005\u4e0e\u5168\u7403\u5a92\u4f53\u7684\u9ad8\u5ea6\u5173\u6ce8\u4e0e\u652f\u6301\u3002 &nbsp; \u6d77\u5916\u5206\u652f\u793e\u533a\u7684\u84ec\u52c3\u53d1\u5c55\u00a0 \u6700\u8fd1\uff0cdeepin \u5728\u56fd\u9645\u5316\u8fdb\u7a0b\u4e2d\u53c8\u8fc8\u51fa\u4e86\u575a\u5b9e\u7684\u4e00\u6b65\u2014\u2014deepin \u5384\u74dc\u591a\u5c14\u6d77\u5916\u5206\u652f\u793e\u533a\u6b63\u5f0f\u6210\u7acb\uff01\u793e\u533a\u7531\u5384\u74dc\u591a\u5c14\u96c5\u624d\u7406\u5de5\u5927\u5b66\uff08Yachay Tech University\uff09\u81ea\u53d1\u5efa\u7acb\uff0c\u8fd9\u4e00\u6210\u679c\uff0c\u4e0d\u4ec5\u6807\u5fd7\u7740  ...<a href=https:\/\/www.deepin.cn\/zh\/deepin-23-receives-global-user-support\/>\u9605\u8bfb\u66f4\u591a<\/a><\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[144,153,148,141,147,143,162,184],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34825"}],"collection":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/comments?post=34825"}],"version-history":[{"count":6,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34825\/revisions"}],"predecessor-version":[{"id":34845,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34825\/revisions\/34845"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/media?parent=34825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/categories?post=34825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/tags?post=34825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}