{"id":34267,"date":"2024-07-18T13:57:33","date_gmt":"2024-07-18T05:57:33","guid":{"rendered":"https:\/\/www.deepin.org\/?p=34267"},"modified":"2024-07-18T15:47:30","modified_gmt":"2024-07-18T07:47:30","slug":"deepin-m1-updates-to-rc2","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/zh\/deepin-m1-updates-to-rc2\/","title":{"rendered":"\u65b0\u8fdb\u5c55\uff01deepin M1 \u9879\u76ee\u66f4\u65b0\u81f3 deepin V23 RC2\u7248\u672c"},"content":{"rendered":"<img loading=\"lazy\" class=\"alignnone size-full wp-image-34268\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/640-1.jpeg\" alt=\"\" width=\"900\" height=\"383\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1.jpeg 900w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-300x128.jpeg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-150x64.jpeg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-768x327.jpeg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-24x10.jpeg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-36x15.jpeg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/640-1-48x20.jpeg 48w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>\u5728\u53bb\u5e747\u6708\u4efd\uff0c\u6211\u4eec\u6210\u529f\u4f7f deepin \u521d\u6b65\u9002\u914d\u4e86Apple M1 \u3002\u4eca\u5e74\u968f\u7740deepin V23 beta\u8fdb\u5165RC2\u7248\u672c\uff0cdeepin M1\u9879\u76ee\u7406\u6240\u5f53\u7136\u5730\u4e5f\u4f1a\u8ddf\u8fdb\u66f4\u65b0\u3002<\/p>\n<p>\u9664\u6b64\u4e4b\u5916\uff0c\u672c\u6b21\u9002\u914d\u5de5\u4f5c\u4e0d\u4ec5\u9650\u4e8e\u63d0\u5347\u7cfb\u7edf\u73af\u5883\u7248\u672c\uff0c\u8fd8\u987a\u5e26\u66f4\u65b0\u4e86\u4e00\u4e9b\u7cfb\u7edf\u5e95\u5c42\u7ec4\u4ef6\u7248\u672c\uff0c\u4f18\u5316\u4e86\u9879\u76ee\u5404\u6a21\u5757\u7684\u6253\u5305\u6d41\u7a0b\u5e76\u90e8\u5206\u6dfb\u52a0\u4e86\u5b9a\u65f6\u5668\uff0c\u6bcf\u5468\u6784\u5efa\u4e00\u6b21\u5185\u5bb9\u4ee5\u4fbf\u5f00\u53d1\u8005\u62a2\u5148\u4f53\u9a8c\u5c1d\u9c9c\u3002\u4e0b\u9762\uff0c\u5c31\u5f00\u59cb\u8be6\u7ec6\u4ecb\u7ecd\u672c\u6b21\u66f4\u65b0\u7684\u5177\u4f53\u5185\u5bb9\u3002<\/p>\n<p><a href=\"https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-1\/\">\u300adeepin\u6210\u529f\u9002\u914dApple M1\uff0c\u6211\u4eec\u7684\u9002\u914d\u4e4b\u65c5\uff01(\u4e0a\u7bc7)\u300b<\/a><\/p>\n<p><a href=\"https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-2\/\">\u300adeepin\u6210\u529f\u9002\u914dApple M1\uff0c\u6211\u4eec\u7684\u9002\u914d\u4e4b\u65c5\uff01(\u4e0b\u7bc7)\u300b<\/a><\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>\u7cfb\u7edf\u73af\u5883<\/strong><\/h1>\n<p>\u6700\u65b0\u7684\u7cfb\u7edf\u73af\u5883\u5982\u4e0b\uff1a<\/p>\n<div class=\"su-table su-table-alternate\">\n<table>\n<tbody>\n<tr class=\"ue-table-interlace-color-single\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>\n<p style=\"text-align: center;\"><strong>\u7ec4\u4ef6<\/strong><\/p>\n<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>\n<p style=\"text-align: center;\"><strong>\u7248\u672c<\/strong><\/p>\n<\/section>\n<\/td>\n<\/tr>\n<tr class=\"ue-table-interlace-color-double\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>deepin rootfs \u73af\u5883<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>RC2 (20240614\u65e5\u6784\u5efa)<\/section>\n<\/td>\n<\/tr>\n<tr class=\"ue-table-interlace-color-single\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>linux-image-asahi<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>6.8.9-6<\/section>\n<\/td>\n<\/tr>\n<tr class=\"ue-table-interlace-color-double\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>m1n1<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>1.4.14<\/section>\n<\/td>\n<\/tr>\n<tr class=\"ue-table-interlace-color-single\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>uboot<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>asahi-v2024.04-1<\/section>\n<\/td>\n<\/tr>\n<tr class=\"ue-table-interlace-color-double\">\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>mesa<\/section>\n<\/td>\n<td align=\"left\" valign=\"middle\" width=\"269\">\n<section>24.1.0-asahi-20240228<\/section>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<section>\u66f4\u65b0\u8fc7\u540e\u7684rootfs\uff0c\u5df2\u786e\u5b9a\u652f\u6301\u5728Mac mini M1\u7684\u6700\u65b014.5\u7248\u672c\u4e0a\u6210\u529f\u5b89\u88c5\u542f\u52a8\u3002\u53e6\u5916\uff0c\u7531\u4e8edeepin V23 ARM64 \u7a33\u5b9a\u4ed3\u5e93\u7684\u8f6f\u4ef6\u5305\u7248\u672c\u5df2\u7ecf\u66f4\u65b0\u5230\u4e86\u8db3\u4ee5\u4e0edeepin M1\u7279\u6709\u7ec4\u4ef6\u76f8\u517c\u5bb9\u7684\u7a0b\u5ea6\uff0c\u4e0d\u518d\u9700\u8981\u6fc0\u8fdb\u4f46\u4e0d\u592a\u7a33\u5b9a\u7684CI\u4ed3\u5e93\u6765\u6784\u5efa\u7cfb\u7edf\u73af\u5883\u3002\u6240\u4ee5\uff0c\u5728\u672c\u6b21\u66f4\u65b0\u4e4b\u540e\uff0cdeepin M1\u7684\u7cfb\u7edf\u5c06\u5207\u6362\u5230\u7a33\u5b9a\u5e93\u3002<\/section>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34269 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735.jpg\" alt=\"\" width=\"1918\" height=\"1079\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735.jpg 1918w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-300x169.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-1024x576.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-150x84.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-768x432.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-1536x864.jpg 1536w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-24x14.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-36x20.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134735-48x27.jpg 48w\" sizes=\"(max-width: 1918px) 100vw, 1918px\" \/><\/p>\n<p>\u5f97\u76ca\u4e8e\u5b89\u88c5\u5668\u7684\u76f8\u5173Bug\u4fee\u590d\uff0c\u73b0\u5728\u5728\u811a\u672c\u5b89\u88c5\u5b8c\u6210\u540e\u7b2c\u4e00\u6b21\u542f\u52a8\u65f6\u663e\u793a\u5b89\u88c5\u5668\u540e\u914d\u7f6e\u6210\u4e3a\u4e86\u53ef\u80fd\u3002\u56e0\u6b64\uff0cdeepin M1\u73b0\u5df2\u53d6\u6d88\u4e86\u9ed8\u8ba4\u7528\u6237\u8d26\u53f7\uff0c\u6539\u4e3a\u5b89\u88c5\u540e\u7b2c\u4e00\u6b21\u542f\u52a8\u65f6\u914d\u7f6e\u5e10\u6237\u3002\u5927\u5bb6\u518d\u4e5f\u4e0d\u9700\u8981\u7ea0\u7ed3\u9ed8\u8ba4\u5bc6\u7801\u662f\u4ec0\u4e48\u4e86\u3002<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34270 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815.jpg\" alt=\"\" width=\"1919\" height=\"1003\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815.jpg 1919w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-300x157.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-1024x535.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-150x78.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-768x401.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-1536x803.jpg 1536w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-24x13.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-36x19.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134815-48x25.jpg 48w\" sizes=\"(max-width: 1919px) 100vw, 1919px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>\u5e95\u5c42\u7ec4\u4ef6\u66f4\u65b0<\/strong><\/h1>\n<p>m1n1\u548cuboot\u5747\u5df2\u66f4\u65b0\u81f3\u4e0a\u6e38\u6700\u65b0\u7248\u672c\uff0c\u9664\u4e86\u5e26\u6765\u5728\u6700\u65b0MacOS\u7cfb\u7edf\u4e0a\u542f\u52a8\u7684\u80fd\u529b\u4ee5\u5916\uff0c\u8fd8\u89e3\u51b3\u4e86\u56f0\u6270\u5df2\u4e45\u7684\u7cfb\u7edf\u542f\u52a8\u83dc\u5355\u754c\u9762\u952e\u76d8\u65e0\u6cd5\u64cd\u4f5c\u7684\u95ee\u9898\u3002<\/p>\n<p>Linux\u5185\u6838\u548cMesa\u5728\u66f4\u65b0\u81f3\u5f53\u524d\u6700\u65b0\u7a33\u5b9a\u7248\u672c\u7684\u540c\u65f6\uff0c\u8fd8\u4f7f\u7528\u4e86\u4e0e\u4e0a\u6e38\u4fdd\u6301\u4e00\u81f4\u7684\u65b0\u7248\u672cRust\u6765\u8fdb\u884c\u7f16\u8bd1\u6253\u5305\u3002\u9664\u6b64\u4e4b\u5916\uff0c\u8fd8\u6539\u7528\u4e86\u53cd\u590d\u8c03\u8bd5\u51fa\u7684\u6700\u4f73\u6784\u5efa\u9009\u9879\u3002\u7ed3\u679c\u4fbf\u662f\uff0c\u5f53\u524d\u4ed3\u5e93\u4e2d\u6700\u65b0\u7684Linux\u5185\u6838\u5df2\u7ecf\u53ef\u4ee5\u652f\u6301GPU\u786c\u4ef6\u52a0\u901f\u4e86\u3002\u8fd9\u4e5f\u610f\u5473\u7740\u7cfb\u7edf\u754c\u9762\u5c06\u4f1a\u66f4\u52a0\u4e1d\u6ed1\u6d41\u7545\uff0c\u6e38\u620f\u4f53\u9a8c\u4e5f\u4f1a\u66f4\u597d<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34271 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822.jpg\" alt=\"\" width=\"1919\" height=\"762\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822.jpg 1919w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-300x119.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-1024x407.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-150x60.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-768x305.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-1536x610.jpg 1536w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-24x10.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-36x14.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134822-48x19.jpg 48w\" sizes=\"(max-width: 1919px) 100vw, 1919px\" \/><\/p>\n<p>\u6b64\u5916\uff0c\u4e00\u76f4\u4ee5\u6765\u7684USB\u8f93\u5165\u8bbe\u5907\u81ea\u52a8\u4f11\u7720\u95ee\u9898\u4e5f\u5728\u65b0\u7248\u5185\u6838\u91cc\u7ed9\u4e00\u5e76\u4fee\u590d\u4e86\u3002<\/p>\n<p>&nbsp;<\/p>\n<section>\n<section>\n<h1 style=\"text-align: center;\"><strong data-brushtype=\"text\">\u65b0\u589e\u6784\u5efa\u6d41\u7a0b<\/strong><\/h1>\n<\/section>\n<\/section>\n<p>\u5f97\u76ca\u4e8edeepin-rootfs\u548cdeepin-docker\u9879\u76ee\u7684\u51fa\u73b0\uff0c\u73b0\u5728\u6253\u5305deepin-m1\u7684\u7ec4\u4ef6\u6709\u4e86deepin\u57fa\u7840\u73af\u5883\u4e86\u3002\u5176\u6210\u679c\u4fbf\u662f\u76ee\u524d\u505a\u51fa\u6765\u7684\uff0c\u5206\u522b\u7528\u4e8e\u6253\u5305rootfs\uff0c\u5185\u6838\u4e0em1n1\uff0cUSB\u542f\u52a8\u76d8\u5185\u5bb9\u7684\u4e09\u4e2a\u6784\u5efa\u6d41\u7a0b\u3002<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34272 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826.jpg\" alt=\"\" width=\"1671\" height=\"944\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826.jpg 1671w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-300x169.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-1024x578.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-150x85.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-768x434.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-1536x868.jpg 1536w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-24x14.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-36x20.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134826-48x27.jpg 48w\" sizes=\"(max-width: 1671px) 100vw, 1671px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u4e09\u4e2a\u6784\u5efa\u90fd\u662fpush\u64cd\u4f5c\u89e6\u53d1\uff0c\u800crootfs\u548cUSB\u542f\u52a8\u5185\u5bb9\u6784\u5efa\u8fd8\u53e6\u5916\u6dfb\u52a0\u4e86\u6bcf\u5468\u4e00\u7684\u5b9a\u65f6\u89e6\u53d1\u5668\u3002\u6709\u9700\u8981\u7684\u7528\u6237\uff0c\u53ef\u4ee5\u76f4\u63a5\u53bb\u9879\u76ee\u9875\u9762Actions\u4e2d\u7684\u6700\u65b0\u6784\u5efa\u5386\u53f2\u91cc\u4e0b\u8f7d\u672c\u5468\u6253\u5305\u7684\u955c\u50cf\u3002<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-34273 aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830.jpg\" alt=\"\" width=\"1909\" height=\"904\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830.jpg 1909w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-300x142.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-1024x485.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-150x71.jpg 150w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-768x364.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-1536x727.jpg 1536w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-24x11.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-36x17.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2024\/07\/\u5fae\u4fe1\u56fe\u7247_20240718134830-48x23.jpg 48w\" sizes=\"(max-width: 1909px) 100vw, 1909px\" \/><\/p>\n<p>\u53e6\u5916\u9700\u8981\u8bf4\u660e\u7684\u662f\uff0c\u56e0\u4e3agithub action runner\u7684\u9650\u5236\uff0c\u6253\u5305rootfs\u9700\u8981\u8fdb\u884c\u4e00\u5b9a\u5730\u7cbe\u7b80\u4ee5\u8282\u7ea6\u78c1\u76d8\u7a7a\u95f4\uff0c\u6240\u4ee5deepin-base\u7684\u6253\u5305\u88ab\u9ed8\u8ba4\u5173\u95ed\u4e86\u3002\u6709\u9700\u8981\u7684\u5f00\u53d1\u8005\u53ef\u4ee5\u81ea\u884c\u4fee\u6539bootstrap.sh\u4e2d\u7684\u76f8\u5173\u90e8\u5206\u5f00\u542f\u3002<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\">\u4e0b\u4e00\u6b65\u7684\u5de5\u4f5c<\/h1>\n<p>\u5f53\u524d\uff0c\u4ecd\u7136\u5b58\u5728\u7740\u8bb8\u591a\u95ee\u9898\u3002\u5176\u4e2d\u6700\u5f71\u54cd\u65e5\u5e38\u4f53\u9a8c\u7684\u4e00\u4e2a\u4fbf\u662f\u6ca1\u6709\u58f0\u97f3\u7684Bug\u3002\u76ee\u524d\uff0c\u6b63\u5728\u6392\u67e5\u5f53\u4e2d\u3002\u9700\u8981\u64ad\u653e\u58f0\u97f3\u7684\u7528\u6237\uff0c\u53ef\u4ee5\u901a\u8fc7\u5b89\u88c5alsa-ucm-conf-asahi\u6765\u75283.5mm\u63a5\u53e3\u653e\u58f0\u97f3\u3002<\/p>\n<p>\u4e0d\u4e45\u4e4b\u524d\uff0cAsahi\u5b98\u65b9\u5ba3\u5e03\u4e86\u4ed6\u4eec\u652f\u6301Vulkan\u7684\u8fdb\u5ea6\u3002\u6211\u4eec\u4e5f\u5c06\u6301\u7eed\u5173\u6ce8\u8ddf\u8fdb\uff0c\u5e76\u5728\u7a33\u5b9a\u7248\u91ca\u51fa\u4e4b\u540e\uff0c\u5c3d\u5feb\u66f4\u65b0Mesa.\u3002<\/p>\n<p>\u5f53\u524d\u7684ARM64\u8f6f\u4ef6\u751f\u6001\u8fd8\u662f\u76f8\u5bf9\u8584\u5f31\u7684\u3002\u672a\u6765\u5c06\u4f1a\u548cdeepin-sysdev-sig\uff0cdeepin-arm-pc\u7b49\u7ec4\u7ec7\u534f\u4f5c\uff0c\u5f15\u5165\u66f4\u591a\u7684\u8f6f\u4ef6\u5305\u6765\u6269\u5145\u53ef\u7528\u8f6f\u4ef6\u5185\u5bb9\u3002<\/p>\n<p>box64\u81ea0.2.6\u7248\u672c\u4e4b\u540e\uff0c\u4fbf\u80fd\u591f\u5728Mac M\u7cfb\u5217Soc\u4e0a\u8fd0\u884c\u4e86\u3002\u8fd9\u610f\u5473\u7740\u5b83\u53ef\u4ee5\u901a\u8fc7box64\u548cwine wow64\u6765\u652f\u6301Linux\u548cWindows\u7684x86_64\u7a0b\u5e8f\u3002\u5f53\u524d\u8fd9\u4e24\u4e2a\u8f6f\u4ef6\u90fd\u6ca1\u6709\u6253\u5305\u3002\u672a\u6765\u4f1a\u5c1d\u8bd5\u6dfb\u52a0\u8fdbdeepin\u4ed3\u5e93\u7684\u3002<\/p>\n<p><strong data-brushtype=\"text\">\u5199\u5728\u6700\u540e\uff1a<\/strong><\/p>\n<p>\u6700\u540e\uff0c\u518d\u6b21\u611f\u8c22deepin\u76f8\u5173SIG\u7ec4\u7684\u5f00\u53d1\u8005\uff0c\u975e\u5e38\u611f\u8c22\u4f60\u4eec\u5728Asahi Linux\u4ee5\u53cam1-debian\u9879\u76ee\u7684\u534f\u52a9\u4e0e\u652f\u6301\u3002\u6b63\u662f\u7531\u4e8e\u4f60\u4eec\u7684\u8d21\u732e\u5f00\u6e90\u3001\u53c2\u4e0e\u5f00\u6e90\uff0cdeepin\u7cfb\u7edf\u624d\u4f1a\u8d8a\u6765\u8d8a\u7f8e\u597d\u3002\u8c22\u8c22\u4f60\u4eec\uff01<\/p>\n<p>&nbsp;<\/p>\n<h1><strong>\u9644\u5f55\uff1a<\/strong><\/h1>\n<p>\uff081\uff09deepin-m1 SIG\u7ec4\u5165\u53e3\uff1a<a href=\"https:\/\/www.deepin.org\/index\/docs\/sig\/sig\/deepin-m1\/README\">https:\/\/www.deepin.org\/index\/docs\/sig\/sig\/deepin-m1\/README<\/a><\/p>\n<p>\uff082\uff09deepin-m1\u9879\u76ee\u5730\u5740\uff1a<a href=\"https:\/\/github.com\/deepin-community\/deepin-m1\">https:\/\/github.com\/deepin-community\/deepin-m1<\/a><\/p>\n<p>\uff083\uff09deepin\u6210\u529f\u9002\u914dApple M1\uff0c\u6211\u4eec\u7684\u9002\u914d\u4e4b\u65c5\uff01(\u4e0a\u7bc7)\uff1a<a href=\"https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-1\/\">https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-1\/<\/a><\/p>\n<p>\uff084\uff09deepin\u6210\u529f\u9002\u914dApple M1\uff0c\u6211\u4eec\u7684\u9002\u914d\u4e4b\u65c5\uff01(\u4e0b\u7bc7)\uff1a<a href=\"https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-2\/\">https:\/\/www.deepin.org\/zh\/deepin-adapted-applem1-2\/<\/a><\/p>\n<p>\uff085\uff09deepin \u5168\u7248\u672c\u955c\u50cf\uff08\u542b deepin V15\uff09\uff1a<a href=\"https:\/\/distrowatch.com\/index.php?distribution=deepin\">https:\/\/distrowatch.com\/index.php?distribution=deepin<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">\u5185\u5bb9\u6765\u6e90\uff1adeepin\uff08\u6df1\u5ea6\uff09\u793e\u533a<\/p>\n<p style=\"text-align: right;\">\u8f6c\u8f7d\u8bf7\u6ce8\u660e\u51fa\u5904<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5728\u53bb\u5e747\u6708\u4efd\uff0c\u6211\u4eec\u6210\u529f\u4f7f deepin \u521d\u6b65\u9002\u914d\u4e86Apple M1 \u3002\u4eca\u5e74\u968f\u7740deepin V23 beta\u8fdb\u5165RC2\u7248\u672c\uff0cdeepin M1\u9879\u76ee\u7406\u6240\u5f53\u7136\u5730\u4e5f\u4f1a\u8ddf\u8fdb\u66f4\u65b0\u3002 \u9664\u6b64\u4e4b\u5916\uff0c\u672c\u6b21\u9002\u914d\u5de5\u4f5c\u4e0d\u4ec5\u9650\u4e8e\u63d0\u5347\u7cfb\u7edf\u73af\u5883\u7248\u672c\uff0c\u8fd8\u987a\u5e26\u66f4\u65b0\u4e86\u4e00\u4e9b\u7cfb\u7edf\u5e95\u5c42\u7ec4\u4ef6\u7248\u672c\uff0c\u4f18\u5316\u4e86\u9879\u76ee\u5404\u6a21\u5757\u7684\u6253\u5305\u6d41\u7a0b\u5e76\u90e8\u5206\u6dfb\u52a0\u4e86\u5b9a\u65f6\u5668\uff0c\u6bcf\u5468\u6784\u5efa\u4e00\u6b21\u5185\u5bb9\u4ee5\u4fbf\u5f00\u53d1\u8005\u62a2\u5148\u4f53\u9a8c\u5c1d\u9c9c\u3002\u4e0b\u9762\uff0c\u5c31\u5f00\u59cb\u8be6\u7ec6\u4ecb\u7ecd\u672c\u6b21\u66f4\u65b0\u7684\u5177\u4f53\u5185\u5bb9\u3002 \u300adeepin\u6210\u529f ...<a href=https:\/\/www.deepin.cn\/zh\/deepin-m1-updates-to-rc2\/>\u9605\u8bfb\u66f4\u591a<\/a><\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155,93],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34267"}],"collection":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/comments?post=34267"}],"version-history":[{"count":4,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34267\/revisions"}],"predecessor-version":[{"id":34279,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34267\/revisions\/34279"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/media?parent=34267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/categories?post=34267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/tags?post=34267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}