{"id":329,"date":"2011-12-25T19:28:36","date_gmt":"2011-12-25T11:28:36","guid":{"rendered":"https:\/\/www.deepin.org\/?p=329"},"modified":"2011-12-25T19:28:36","modified_gmt":"2011-12-25T11:28:36","slug":"bug-about-app-name","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/zh\/bug-about-app-name\/","title":{"rendered":"\u4fee\u590d\u5c0fBUG\u4e00\u679a\uff1a\u5e94\u7528\u540d\u79f0\u4e0d\u80fd\u5168\u90e8\u663e\u793a"},"content":{"rendered":"<p>\u738b\u52c7\uff1a\u76ee\u524d\u4fee\u590dgnome shell \u63a7\u5236\u9762\u677f\u4e2d\u5e94\u7528\u540d\u79f0\u4e0d\u80fd\u5168\u90e8\u663e\u793a\u7684\u95ee\u9898<\/p>\n<p>\u5982\u56fe\uff1a<\/p>\n<p><a href=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/name.jpg\"><img loading=\"lazy\" class=\" wp-image-330 aligncenter\" title=\"name\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/name-1024x575.jpg\" alt=\"\" width=\"749\" height=\"421\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u738b\u52c7\uff1a\u76ee\u524d\u4fee\u590dgnome shell \u63a7\u5236\u9762\u677f\u4e2d\u5e94\u7528\u540d\u79f0\u4e0d\u80fd\u5168\u90e8\u663e\u793a\u7684\u95ee\u9898 \u5982\u56fe\uff1a<\/p>\n","protected":false},"author":27,"featured_media":9982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[93],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/329"}],"collection":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/comments?post=329"}],"version-history":[{"count":0,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/media?parent=329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/categories?post=329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/tags?post=329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}