{"id":22502,"date":"2017-03-30T15:29:17","date_gmt":"2017-03-30T07:29:17","guid":{"rendered":"https:\/\/www.deepin.org\/?p=22502"},"modified":"2017-03-30T15:29:17","modified_gmt":"2017-03-30T07:29:17","slug":"activity-review-for-whlug-on-march-29-2017","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/zh\/activity-review-for-whlug-on-march-29-2017\/","title":{"rendered":"2017\u5e7403\u670829\u65e5\u6b66\u6c49Linux\u7528\u6237\u7ec4\u6d3b\u52a8\u56de\u987e"},"content":{"rendered":"<p style=\"text-align: left;\">\u7b2c\u4e8c\u671fWHLUG\u6d3b\u52a8\u4e8e2017\u5e743\u670829\u65e5\u5468\u4e0919:00-21\uff1a00\u5728\u5149\u8c37\u6b65\u884c\u8857\u65c5\u5f92\u5496\u5561\u9986\u8fdb\u884c\uff01\u6b64\u6b21\u6f14\u8bb2\u5609\u5bbe\u4e3adeepin\u5f00\u53d1\u5de5\u7a0b\u5e08\u738b\u8000\u534e\uff0c\u4e3b\u9898\u4e3a\u6df1\u5ea6\u64cd\u4f5c\u7cfb\u7edf\u63a7\u5236\u4e2d\u5fc3\u7684\u67b6\u6784\u8bbe\u8ba1\u7b80\u8ff0\u3002<\/p>\n<p style=\"text-align: left;\">\u4e0b\u9762\u8bf7\u8ddf\u968f\u6211\u56de\u987e\u6574\u4e2a\u6d3b\u52a8\u5427\u3002<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22507 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-1809411.jpg\" alt=\"P70329-180941(1)\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-1809411-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u6d3b\u52a8\u573a\u5730<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"wp-image-22508 size-full aligncenter\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-191153.jpg\" alt=\"P70329-191153\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-191153-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u5176\u4e50\u878d\u878d<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22509 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-192002.jpg\" alt=\"P70329-192002\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192002-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u6211\u4eec\u7684\u773c\u4e2d\u771f\u7684\u53ea\u6709\u4ee3\u7801<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22530 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-192059-1.jpg\" alt=\"P70329-192059\" width=\"3120\" height=\"4208\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1.jpg 3120w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-222x300.jpg 222w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-768x1036.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-759x1024.jpg 759w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-18x24.jpg 18w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-27x36.jpg 27w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-192059-1-36x48.jpg 36w\" sizes=\"(max-width: 3120px) 100vw, 3120px\" \/><\/p>\n<p style=\"text-align: center;\">\u8d44\u6df1linux\u73a9\u5bb6\uff0c\u7279\u610f\u8fc7\u6765\u770b\u770b\u6b66\u6c49linuxer\u4eec<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22516 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-194122.jpg\" alt=\"P70329-194122\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194122-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u5316\u5b66\u4e13\u4e1a\u5c0f\u840c\u65b0<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22518 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-194400.jpg\" alt=\"P70329-194400\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194400-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u4f20\u8bf4\u4e2d\u7684\u7af9\u5b50\u548c\u80a5\u732b<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22519 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-194831.jpg\" alt=\"P70329-194831\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194831-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u8170\u82b1\u5c31\u662fHualet<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22520 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-194948.jpg\" alt=\"P70329-194948\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-194948-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u6a21\u5757\u5316\u8bbe\u8ba1<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22528 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-195657.jpg\" alt=\"P70329-195657\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-195657-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u73b0\u573a\u6539\u4e86\u4e2aBug<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22515 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-193423.jpg\" alt=\"P70329-193423\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-193423-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">Bug\u4f60\u4eec\u5c3d\u7ba1\u627e\uff0c\u627e\u4e0d\u51fa\u6765\u7b97\u6211\u8f93<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22523 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-201801.jpg\" alt=\"P70329-201801\" width=\"3120\" height=\"4208\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801.jpg 3120w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-222x300.jpg 222w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-768x1036.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-759x1024.jpg 759w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-18x24.jpg 18w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-27x36.jpg 27w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201801-36x48.jpg 36w\" sizes=\"(max-width: 3120px) 100vw, 3120px\" \/><\/p>\n<p style=\"text-align: center;\">\u8bf7\u95eewine\uff0ccrossover\uff0cdeepin-wine\u7684\u533a\u522b<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22525 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-201823.jpg\" alt=\"P70329-201823\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201823-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u770b\u6211\u4e00\u4e00\u5411\u4f60\u9053\u6765<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22524 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-201603.jpg\" alt=\"P70329-201603\" width=\"3120\" height=\"4208\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603.jpg 3120w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-222x300.jpg 222w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-768x1036.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-759x1024.jpg 759w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-18x24.jpg 18w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-27x36.jpg 27w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-201603-36x48.jpg 36w\" sizes=\"(max-width: 3120px) 100vw, 3120px\" \/><\/p>\n<p style=\"text-align: center;\">\u80a5\u732b\u6700\u5173\u5fc3\u7684\u662f\u600e\u6837\u80fd\u8ba9\u52a0\u8f7d\u901f\u5ea6\u66f4\u5feb<\/p>\n<p>&nbsp;<br \/>\n<img loading=\"lazy\" class=\"aligncenter wp-image-22526 size-full\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2017\/03\/P70329-202933.jpg\" alt=\"P70329-202933\" width=\"4208\" height=\"3120\" srcset=\"https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933.jpg 4208w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-300x222.jpg 300w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-768x569.jpg 768w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-1024x759.jpg 1024w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-24x18.jpg 24w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-36x27.jpg 36w, https:\/\/www.deepin.cn\/wp-content\/uploads\/2017\/03\/P70329-202933-48x36.jpg 48w\" sizes=\"(max-width: 4208px) 100vw, 4208px\" \/><\/p>\n<p style=\"text-align: center;\">\u8170\u82b1\u4f4e\u5934\u7b11\u7740\u8bf4\u6211\u4eec\u5230\u4e0b\u4e00\u4e2a\u73af\u8282\u5427<\/p>\n<p>&nbsp;","protected":false},"excerpt":{"rendered":"<p>\u7b2c\u4e8c\u671fWHLUG\u6d3b\u52a8\u4e8e2017\u5e743\u670829\u65e5\u5468\u4e0919:00-21\uff1a00\u5728\u5149\u8c37\u6b65\u884c\u8857\u65c5\u5f92\u5496\u5561\u9986\u8fdb\u884c\uff01\u6b64\u6b21\u6f14\u8bb2\u5609\u5bbe\u4e3adeepin\u5f00\u53d1\u5de5\u7a0b\u5e08\u738b\u8000\u534e\uff0c\u4e3b\u9898\u4e3a\u6df1\u5ea6\u64cd\u4f5c\u7cfb\u7edf\u63a7\u5236\u4e2d\u5fc3\u7684\u67b6\u6784\u8bbe\u8ba1\u7b80\u8ff0\u3002 \u4e0b\u9762\u8bf7\u8ddf\u968f\u6211\u56de\u987e\u6574\u4e2a\u6d3b\u52a8\u5427\u3002 \u6d3b\u52a8\u573a\u5730 &nbsp; \u5176\u4e50\u878d\u878d &nbsp; \u6211\u4eec\u7684\u773c\u4e2d\u771f\u7684\u53ea\u6709\u4ee3\u7801 &nbsp; \u8d44\u6df1linux\u73a9\u5bb6\uff0c\u7279\u610f\u8fc7\u6765\u770b\u770b\u6b66\u6c49linuxer\u4eec &nbsp; \u5316\u5b66\u4e13\u4e1a\u5c0f\u840c\u65b0 &nbsp; \u4f20 ...<a href=https:\/\/www.deepin.cn\/zh\/activity-review-for-whlug-on-march-29-2017\/>\u9605\u8bfb\u66f4\u591a<\/a><\/p>\n","protected":false},"author":141,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[118],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/22502"}],"collection":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/comments?post=22502"}],"version-history":[{"count":6,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/22502\/revisions"}],"predecessor-version":[{"id":22534,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/22502\/revisions\/22534"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/media?parent=22502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/categories?post=22502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/tags?post=22502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}