{"id":19478,"date":"2011-12-20T18:25:55","date_gmt":"2011-12-20T10:25:55","guid":{"rendered":"https:\/\/www.deepin.org\/?p=308"},"modified":"2011-12-20T18:25:55","modified_gmt":"2011-12-20T10:25:55","slug":"cairo-graph-for-python-3-cairo-backend","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/zh\/cairo-graph-for-python-3-cairo-backend\/","title":{"rendered":"Cairo \u56fe\u5f62\u6307\u5357 for Python (3) \u2014\u2014 Cairo \u540e\u7aef"},"content":{"rendered":"<p><strong>\u4f5c\u8005<\/strong>\uff1a\u4faf\u5c11\u8f89\uff0cLD \u5f00\u53d1\u8005\uff0c\u672c\u6587\u539f\u8f7d<a href=\"http:\/\/www.linuxdeepin.com\/forum\/21\/3989\" target=\"_blank\">Linux Deepin \u8bba\u575b<\/a><\/p>\n<p>Cairo \u652f\u6301\u591a\u79cd\u540e\u7aef\uff0cCairo \u652f\u6301\u591a\u79cd\u540e\u7aef\uff0c\u672c\u6587\u57fa\u4e8e\u51e0\u4e2a\u793a\u4f8b\u8bb2\u8ff0\u5982\u4f55\u4f7f\u7528 Cairo \u5404\u79cd\u540e\u7aef\u521b\u5efa PNG \u56fe\u50cf\u3001PDF \u6587\u4ef6\u4e0e SVG \u6587\u4ef6\u4ee5\u53ca\u5982\u4f55\u4f7f\u7528 Cairo \u5728 GTK \u7a97\u53e3\u4e2d\u7ed8\u56fe\u3002<\/p>\n<p><strong>1.<\/strong> PNG \u56fe\u50cf\u7b2c\u4e00\u4e2a\u793a\u4f8b (example-1.c) \u7528\u4e8e\u751f\u6210 PNG \u56fe\u50cf\u3002<\/p>\n<pre>import cairo\n\nsurface = cairo.ImageSurface(cairo.FORMAT_ARGB32, 320, 48)\ncr = cairo.Context(surface)\ncr.set_source_rgb(0.627, 0, 0)\ncr.select_font_face('Monospace', cairo.FONT_SLANT_NORMAL, cairo.FONT_WEIGHT_NORMAL)\ncr.set_font_size(24.0)\ncr.move_to(10.0, 34.0)\ncr.show_text(\"\u6700\u597d\u7684\u7528\u7684Linux-linux deepin\")\nsurface.write_to_png('image.png')\n<\/pre>\n<p>\u6548\u679c\u56fe:<br \/> <a href=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/image.png_001.png\"><img class=\"alignnone size-full wp-image-309\" title=\"image.png_001\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/image.png_001.png\" alt=\"\" width=\"442\" \/><\/a><br \/> <!--more--><br \/> \u8fd9\u4e2a\u793a\u4f8b\u662f\u4e00\u4e2a\u5f88\u5c0f\u7684\u63a7\u5236\u53f0\u7a0b\u5e8f\uff0c\u8fd0\u884c\u540e\u53ef\u751f\u6210\u4e00\u4efd PNG \u56fe\u50cf\u6587\u4ef6\u3002<\/p>\n<p><strong>2. <\/strong>PDF \u6587\u4ef6\u5728\u7b2c\u4e8c\u4e2a\u793a\u4f8b (example-2.c) \u4e2d\uff0c\u5c06\u4f7f\u7528 Cairo \u751f\u6210\u4e00\u4efd PDF \u6587\u4ef6\uff0c\u5176\u5185\u5bb9\u4e0e\u7b2c\u4e00\u4e2a\u793a\u4f8b\u6240\u751f\u6210\u7684\u56fe\u50cf\u662f\u76f8\u540c\u7684\u3002<\/p>\n<pre>import cairo\n\n\nsurface = cairo.PDFSurface(\"pdffile.pdf\", 320, 48)\ncr = cairo.Context(surface)\ncr.set_source_rgb(0.627, 0 ,0)\ncr.select_font_face('Monospace', cairo.FONT_SLANT_ITALIC, cairo.FONT_WEIGHT_BOLD)\ncr.set_font_size(24.0)\ncr.move_to(10.0, 34.0)\ncr.show_text(\"\u6df1\u5ea6Linux,\u503c\u5f97\u6df1\u5165\")\ncr.show_page()\n<\/pre>\n<p><strong>3. <\/strong>SVG \u6587\u4ef6\u7b2c\u4e09\u4e2a\u793a\u4f8b\u6f14\u793a\u5982\u4f55\u4f7f\u7528 Cairo SVG \u540e\u7aef\u751f\u6210\u4e00\u4efd\u7b80\u5355\u7684 SVG (Scalble Vector Graphics) \u6587\u4ef6\u3002SVG \u6280\u672f\u8fd1\u51e0\u5e74\u5f88\u70ed\u95e8\u3002<\/p>\n<pre>import cairo\n\nsurface = cairo.SVGSurface('svgfile.svg', 320, 48)\ncr = cairo.Context(surface)\ncr.set_source_rgb(0.627, 0, 0)\ncr.select_font_face('Monospace', cairo.FONT_SLANT_ITALIC,\n        cairo.FONT_WEIGHT_BOLD)\ncr.set_font_size(24.0)\ncr.move_to(10.0, 34.0)\ncr.show_text(\"\u6df1\u5ea6Linux,\u503c\u5f97\u60a8\u6df1\u5165!\")\n<\/pre>\n<p><strong>4. <\/strong>\u5728\u6700\u540e\u8fd9\u4e2a\u793a\u4f8b\u4e2d\uff0c\u6f14\u793a\u5982\u4f55\u5728 GTK \u7a97\u53e3\u4e2d\u4f7f\u7528 Cairo \u7ed8\u5236\u56fe\u5f62\u3002\u57fa\u4e8e GTK \u540e\u7aef\u7684 Cairo \u7ed8\u56fe\u6a21\u578b\u5c06\u8d2f\u7a7f\u4e8e\u672c\u6307\u5357\u3002<\/p>\n<pre>import pygtk\npygtk.require('2.0')\nimport gtk\n\nclass CairoText:\n    def __init__(self):\n        self.window = gtk.Window(gtk.WINDOW_TOPLEVEL)\n        self.window.connect('expose_event', self.on_expose_event)\n        self.window.connect('destroy', lambda w: gtk.main_quit())\n        self.window.set_position(gtk.WIN_POS_CENTER)\n        self.window.set_default_size( 320, 48)\n        self.window.set_app_paintable(True)\n        self.window.show_all()\n    \n    def on_expose_event(self, widget, event,  data=None):\n        cr = widget.window.cairo_create()\n        cr.set_source_rgb(0.627, 0, 0)\n        cr.set_font_size(24.0)\n        cr.move_to(10.0, 34.0)\n        cr.show_text('Linux Deepin')\n    \ndef main():\n    gtk.main()\n\nif __name__ == '__main__':\n    CairoText()\n    main()\n<\/pre>\n<p>\u8fd9\u4e2a\u793a\u4f8b\u7a0b\u5e8f\u8fd0\u884c\u540e\uff0c\u4f1a\u5728\u5c4f\u5e55\u4e2d\u592e\u8df3\u51fa\u4e00\u4e2a GTK+ \u7a97\u53e3\uff0c\u4e0a\u9762\u7ed8\u5236\u4e86\u4e00\u4e32\u6587\u672c\uff0c\u5982\u4e0b\u56fe\u6240\u793a\uff1a<br \/> <em>window 7\u4e0b\u8fd0\u884c\u6548\u679c:<\/em><br \/> <a href=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/QQ\u622a\u56fe20111208041701.png\"><img class=\"alignnone size-full wp-image-310\" title=\"QQ\u622a\u56fe20111208041701\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/QQ\u622a\u56fe20111208041701.png\" alt=\"\" width=\"336\" \/><\/a><\/p>\n<p><em>Linux deepin\u4e0b\u8fd0\u884c\u6548\u679c:<\/em><br \/> <a href=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/linuxd.png\"><img class=\"alignnone size-full wp-image-311\" title=\"linuxd\" src=\"https:\/\/www.deepin.org\/wp-content\/uploads\/2011\/12\/linuxd.png\" alt=\"\" width=\"323\" \/><\/a><\/p>\n<p>\u9996\u5148\u8981import gtk\u5e93<\/p>\n<pre>import gtk<\/pre>\n<p>\u5f53 GTK+\u7a97\u53e3\u88ab\u91cd\u7ed8\u65f6\uff0c\u4f1a\u53d1\u51fa expose-event \u4fe1\u53f7\uff0c\u6211\u4eec\u53ef\u5c06\u8fd9\u4e00\u4fe1\u53f7\u8fde\u63a5\u5230 on_expose_event () \u56de\u8c03\u51fd\u6570\u4e0a\u3002<\/p>\n<pre>self.window.connect('expose_event', self.on_expose_event)<\/pre>\n<p>\u8981\u5728 GTK+ \u7a97\u53e3\u4e2d\u7ed8\u5236 Cairo \u56fe\u5f62\uff0c\u53ef\u4ee5\u4f7f\u7528 GtkDrawingArea widget \u6216\u8005\u66f4\u4e3a\u7b80\u5355\u7684 GtkWindow widget\uff0c\u672c\u4f8b\u9009\u62e9 GtkWindow \u3002\u7531 GtkWindow widget \u5bf9 expose-event \u4fe1\u53f7\u5904\u7406\u540e\uff0c\u9ed8\u8ba4\u8981\u91cd\u65b0\u7ed8\u5236\u7a97\u53e3\u80cc\u666f\uff0c\u8fd9\u4f1a\u5c06\u6211\u4eec\u5728 on_expose_event () \u51fd\u6570\u4e2d\u5b9a\u4e49\u7684 Cairo \u56fe\u5f62\u8986\u76d6\u6389\uff0c\u56e0\u6b64\u9700\u8981\u8c03\u7528 widget_set_app_paintable () \u51fd\u6570\u901a\u77e5 GTK+ \u4e0d\u8981\u8fd9\u4e48\u5e72\u3002\u5982\u679c\u662f\u5728 GtkDrawingArea widget \u4e2d\u7ed8\u5236 Cairo \u56fe\u5f62\uff0c\u5219\u53ef\u7701\u533a\u8fd9\u4e00\u6b65\u3002<\/p>\n<pre>self.window.set_app_paintable(True)<\/pre>\n<p>\u6700\u540eCairo \u56fe\u5f62\u7ed8\u5236\u5de5\u4f5c\u662f\u5728 on_expose_event () \u51fd\u6570\u4e2d\u8fdb\u884c\u7684\uff0c\u5728\u8be5\u51fd\u6570\u4e2d\uff0c\u6211\u4eec\u4e3a GTK+ \u7cfb\u7edf\u521b\u5efa\u4e86\u4e00\u4e2a Cairo \u73af\u5883\uff0c\u5e76\u5728\u8be5\u73af\u5883\u4e2d\u7ed8\u5236\u4e86\u4e00\u884c\u6587\u672c\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>\u4f5c\u8005\uff1a\u4faf\u5c11\u8f89\uff0cLD \u5f00\u53d1\u8005\uff0c\u672c\u6587\u539f\u8f7dLinux Deepin \u8bba\u575b Cairo \u652f\u6301\u591a\u79cd\u540e\u7aef\uff0cCairo \u652f\u6301\u591a\u79cd\u540e\u7aef\uff0c\u672c\u6587\u57fa\u4e8e\u51e0\u4e2a\u793a\u4f8b\u8bb2\u8ff0\u5982\u4f55\u4f7f\u7528 Cairo \u5404\u79cd\u540e\u7aef\u521b\u5efa PNG \u56fe\u50cf\u3001PDF \u6587\u4ef6\u4e0e SVG \u6587\u4ef6\u4ee5\u53ca\u5982\u4f55\u4f7f\u7528 Cairo \u5728 GTK \u7a97\u53e3\u4e2d\u7ed8\u56fe\u3002 1. PNG \u56fe\u50cf\u7b2c\u4e00\u4e2a\u793a\u4f8b (example-1.c) \u7528\u4e8e\u751f\u6210 PNG \u56fe\u50cf\u3002 import cairo surface =  ...<a href=https:\/\/www.deepin.cn\/zh\/cairo-graph-for-python-3-cairo-backend\/>\u9605\u8bfb\u66f4\u591a<\/a><\/p>\n","protected":false},"author":27,"featured_media":9982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[93],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/19478"}],"collection":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/comments?post=19478"}],"version-history":[{"count":0,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/19478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/media?parent=19478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/categories?post=19478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/tags?post=19478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}