{"id":37968,"date":"2025-11-27T16:38:02","date_gmt":"2025-11-27T08:38:02","guid":{"rendered":"https:\/\/www.deepin.org\/?p=37968"},"modified":"2025-11-27T17:02:55","modified_gmt":"2025-11-27T09:02:55","slug":"uos-ai-2-12","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/uos-ai-2-12\/","title":{"rendered":"(\u4e2d\u6587) UOS AI 2.12 \u4e0a\u7ebf\uff01MCP \u670d\u52a1\u81ea\u52a8\u8c03\u7528\uff0cAI \u968f\u822a\u518d\u5347\u7ea7"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/37968\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":18825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37968"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/18825"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=37968"}],"version-history":[{"count":5,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37968\/revisions"}],"predecessor-version":[{"id":37982,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37968\/revisions\/37982"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=37968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=37968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=37968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}