{"id":37663,"date":"2025-10-14T10:16:32","date_gmt":"2025-10-14T02:16:32","guid":{"rendered":"https:\/\/www.deepin.org\/?p=37663"},"modified":"2025-10-14T13:22:56","modified_gmt":"2025-10-14T05:22:56","slug":"deepin-uyoutodo","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/deepin-uyoutodo\/","title":{"rendered":"(\u4e2d\u6587) \u6316\u5230\u5b9d\u4e86\uff01deepin\u5927\u4f6c\u4e3a\u7231\u53d1\u7535\u300c\u6781\u7b80\u5f85\u529e\u795e\u5668\u300d\uff0c\u5b9e\u529b\u989c\u503c\u53cc\u5728\u7ebf"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/37663\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":18825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37663"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/18825"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=37663"}],"version-history":[{"count":4,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37663\/revisions"}],"predecessor-version":[{"id":37680,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/37663\/revisions\/37680"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=37663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=37663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=37663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}