{"id":36656,"date":"2025-05-08T15:36:05","date_gmt":"2025-05-08T07:36:05","guid":{"rendered":"https:\/\/www.deepin.org\/?p=36656"},"modified":"2025-05-08T15:38:37","modified_gmt":"2025-05-08T07:38:37","slug":"deepin-community-monthly-report-2025-4","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/deepin-community-monthly-report-2025-4\/","title":{"rendered":"(\u4e2d\u6587) 4 \u6708\u793e\u533a\u6708\u62a5 | deepin 25 Beta \u6301\u7eed\u653b\u575a\u4e2d \u3001deepin 23.1 \u53d1\u5e03"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/36656\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":18825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[213],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36656"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/18825"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=36656"}],"version-history":[{"count":4,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36656\/revisions"}],"predecessor-version":[{"id":36665,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36656\/revisions\/36665"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=36656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=36656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=36656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}