{"id":36499,"date":"2025-03-31T17:43:03","date_gmt":"2025-03-31T09:43:03","guid":{"rendered":"https:\/\/www.deepin.org\/?p=36499"},"modified":"2025-04-01T18:13:53","modified_gmt":"2025-04-01T10:13:53","slug":"whlug-20250329","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/whlug-20250329\/","title":{"rendered":"(\u4e2d\u6587) WHLUG \u56de\u987e | RISC-V \u9002\u914d\u7834\u5c40+\u5185\u6838\u8d21\u732e\u79d8\u7c4d+\u5de5\u5177\u94fe\u9ed1\u79d1\u6280\uff0c\u5168\u5458\u76f4\u547c\u8fc7\u763e\uff01"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/36499\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":18825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[118],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36499"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/18825"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=36499"}],"version-history":[{"count":5,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36499\/revisions"}],"predecessor-version":[{"id":36524,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/36499\/revisions\/36524"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=36499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=36499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=36499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}