{"id":35511,"date":"2024-11-21T10:33:02","date_gmt":"2024-11-21T02:33:02","guid":{"rendered":"https:\/\/www.deepin.org\/?p=35511"},"modified":"2024-11-21T10:36:56","modified_gmt":"2024-11-21T02:36:56","slug":"over-160000-forum-users","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/over-160000-forum-users\/","title":{"rendered":"(\u4e2d\u6587) \u70ed\u70c8\u795d\u8d3adeepin\uff08\u6df1\u5ea6\uff09\u8bba\u575b\u6ce8\u518c\u7528\u6237\u7a81\u783416\u4e07\uff01"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/35511\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[213],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35511"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=35511"}],"version-history":[{"count":2,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35511\/revisions"}],"predecessor-version":[{"id":35517,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35511\/revisions\/35517"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=35511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=35511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=35511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}