{"id":35267,"date":"2024-11-04T14:03:06","date_gmt":"2024-11-04T06:03:06","guid":{"rendered":"https:\/\/www.deepin.org\/?p=35267"},"modified":"2024-11-06T10:16:58","modified_gmt":"2024-11-06T02:16:58","slug":"wechat-4-0","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/wechat-4-0\/","title":{"rendered":"(\u4e2d\u6587) \u88ab\u95ee\u7206N\u904d\u7684\u5fae\u4fe1 deepin 4.0\u516c\u6d4b\u7248\uff0c\u4ed6\u6765\u4e86\uff01"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/35267\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35267"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=35267"}],"version-history":[{"count":3,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35267\/revisions"}],"predecessor-version":[{"id":35284,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/35267\/revisions\/35284"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=35267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=35267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=35267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}