{"id":34825,"date":"2024-09-20T09:59:55","date_gmt":"2024-09-20T01:59:55","guid":{"rendered":"https:\/\/www.deepin.org\/?p=34825"},"modified":"2024-10-21T10:20:54","modified_gmt":"2024-10-21T02:20:54","slug":"deepin-23-receives-global-user-support","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/deepin-23-receives-global-user-support\/","title":{"rendered":"(\u4e2d\u6587) \u70ed\u7231\u65e0\u56fd\u754c\uff1adeepin 23\u83b7\u5f97\u5168\u7403\u7528\u6237\u7684\u4fe1\u4efb\u4e0e\u652f\u6301"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34825\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[144,153,148,141,147,143,162,184],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34825"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=34825"}],"version-history":[{"count":6,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34825\/revisions"}],"predecessor-version":[{"id":34845,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34825\/revisions\/34845"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=34825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=34825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=34825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}