{"id":34466,"date":"2024-08-14T10:20:56","date_gmt":"2024-08-14T02:20:56","guid":{"rendered":"https:\/\/www.deepin.org\/?p=34466"},"modified":"2024-10-21T10:54:55","modified_gmt":"2024-10-21T02:54:55","slug":"deepin-v23-kunlunbios-setuptool","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/deepin-v23-kunlunbios-setuptool\/","title":{"rendered":"(\u4e2d\u6587) deepin 23\u524d\u77bb\u4e28\u4e0e\u6606\u4ed1\u592a\u79d1\u5b8c\u6210\u6df1\u5ea6\u9002\u914d\uff0c\u5f00\u62d3BIOS\u7ba1\u7406\u65b0\u65f6\u4ee3"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34466\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[207,144,153,148,141,147,143,162,184],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34466"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=34466"}],"version-history":[{"count":2,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34466\/revisions"}],"predecessor-version":[{"id":34494,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34466\/revisions\/34494"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=34466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=34466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=34466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}