{"id":34228,"date":"2024-07-16T13:33:12","date_gmt":"2024-07-16T05:33:12","guid":{"rendered":"https:\/\/www.deepin.org\/?p=34228"},"modified":"2024-07-16T13:40:16","modified_gmt":"2024-07-16T05:40:16","slug":"deepin-meetup-2024-shanghai","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/deepin-meetup-2024-shanghai\/","title":{"rendered":"(\u4e2d\u6587) deepin Meetup \u4e0a\u6d77\u7ad9\u56de\u987e\uff0c\u63ed\u79d8\u5982\u610f\u73b2\u73d1\uff08Linyaps\uff09\u5347\u7ea7\u201c\u5185\u5e55\u201d | \u9644 PPT\u4e0b\u8f7d"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/34228\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":11164,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[168],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34228"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/11164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=34228"}],"version-history":[{"count":5,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34228\/revisions"}],"predecessor-version":[{"id":34254,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/34228\/revisions\/34254"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=34228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=34228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=34228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}