{"id":3100,"date":"2013-08-09T16:42:34","date_gmt":"2013-08-09T16:42:34","guid":{"rendered":"https:\/\/www.deepin.org\/?p=3100"},"modified":"2016-12-12T09:22:27","modified_gmt":"2016-12-12T09:22:27","slug":"updates-for-deepin-software-center-on-august-8th","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/updates-for-deepin-software-center-on-august-8th\/","title":{"rendered":"(\u4e2d\u6587) \u6df1\u5ea6\u8f6f\u4ef6\u4e2d\u5fc3\u63a8\u8350\u8f6f\u4ef6\u66f4\u65b0\u8bf4\u660e(8-8)"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/3100\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":27,"featured_media":9982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/3100"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=3100"}],"version-history":[{"count":0,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/3100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=3100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}