{"id":23006,"date":"2017-04-20T18:04:38","date_gmt":"2017-04-20T10:04:38","guid":{"rendered":"https:\/\/www.deepin.org\/?p=23006"},"modified":"2017-04-20T18:06:22","modified_gmt":"2017-04-20T10:06:22","slug":"activity-review-for-whlug-on-april-19-2017","status":"publish","type":"post","link":"https:\/\/www.deepin.cn\/en\/activity-review-for-whlug-on-april-19-2017\/","title":{"rendered":"(\u4e2d\u6587) 2017\u5e7404\u670819\u65e5\u6b66\u6c49Linux\u7528\u6237\u7ec4\u6d3b\u52a8\u56de\u987e"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.deepin.cn\/zh\/wp-json\/wp\/v2\/posts\/23006\" class=\"qtranxs-available-language-link qtranxs-available-language-link-zh\" title=\"\u4e2d\u6587\">\u4e2d\u6587<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in \u4e2d\u6587.<\/p>\n","protected":false},"author":141,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[118],"tags":[],"_links":{"self":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/23006"}],"collection":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/comments?post=23006"}],"version-history":[{"count":8,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/23006\/revisions"}],"predecessor-version":[{"id":23051,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/posts\/23006\/revisions\/23051"}],"wp:attachment":[{"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/media?parent=23006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/categories?post=23006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deepin.cn\/en\/wp-json\/wp\/v2\/tags?post=23006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}